{"id":9176,"date":"2025-01-28T10:21:23","date_gmt":"2025-01-28T13:21:23","guid":{"rendered":"https:\/\/viajandoconvos.com.ar\/wp\/?p=9176"},"modified":"2025-01-28T10:21:28","modified_gmt":"2025-01-28T13:21:28","slug":"chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt","status":"publish","type":"post","link":"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/","title":{"rendered":"Chubut se suma al registro nacional de Agencias de Viajes de FAEVYT"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Se llev\u00f3 a cabo la firma del convenio de adhesi\u00f3n de la provincia de Chubut al Registro Nacional de Agencias de Viajes -RNAV-, con la presencia de Andr\u00e9s Dey\u00e1, presidente de la Federaci\u00f3n Argentina de Asociaciones de Empresas de Viajes y Turismo \u2013 FAEVYT\u2013, Diego Lapenna, ministro de Turismo y \u00c1reas Protegidas de Chubut; Ezequiel Barberis, vicepresidente primero de FAEVYT, Magal\u00ed Volpi. Subsecretaria de Turismo de la provincia de Chubut y Santiago Sussanich presidente de la Asociaci\u00f3n de Agencias de Viajes de Pen\u00ednsula Vald\u00e9s -AAVyTPV-. La firma del convenio se realiz\u00f3 en el marco de FITUR, Madrid, punto de promoci\u00f3n del turismo argentino.\u00bbNo es casualidad que estemos firmando este convenio en el marco de una de las Feria de turismo m\u00e1s importante del mundo, es un gran paso para seguir fortaleciendo el Registro Nacional de Agencias de Viajes y al turismo argentino de cara al mundo. El RNAV es sin\u00f3nimo de profesionalismo y eso nos posiciona a nivel mundial. Chubut cuenta con atractivos \u00fanicos y es un orgullo que se sume a la larga lista de destinos que adhirieron al Registro\u00bb, se\u00f1al\u00f3 Andr\u00e9s Dey\u00e1, presidente de FAEVYT.Chubut se suma a Tierra del Fuego, La Rioja, Villa Carlos Paz, Santa Cruz, Tucum\u00e1n, Neuqu\u00e9n, Ciudad de Salta, Salta, Entre R\u00edos y Mendoza que ya se encuentran adheridas al RNAV.<a><\/a><a><\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Se llev\u00f3 a cabo la firma del convenio de adhesi\u00f3n de la provincia de Chubut al Registro Nacional de Agencias de Viajes -RNAV-, con la presencia de Andr\u00e9s Dey\u00e1, presidente&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":9177,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chubut se suma al registro nacional de Agencias de Viajes de FAEVYT - Viajando con vos con Quique Colombo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chubut se suma al registro nacional de Agencias de Viajes de FAEVYT - Viajando con vos con Quique Colombo\" \/>\n<meta property=\"og:description\" content=\"Se llev\u00f3 a cabo la firma del convenio de adhesi\u00f3n de la provincia de Chubut al Registro Nacional de Agencias de Viajes -RNAV-, con la presencia de Andr\u00e9s Dey\u00e1, presidente&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/\" \/>\n<meta property=\"og:site_name\" content=\"Viajando con vos con Quique Colombo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quique.colombo\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-28T13:21:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-28T13:21:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/5y3b9zFKNARvgJtdKXRjB8AWYkQAWLo7oHHSC0n8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"734\" \/>\n\t<meta property=\"og:image:height\" content=\"1038\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ViajandoConVos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ViajandoConVos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2025\\\/01\\\/28\\\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2025\\\/01\\\/28\\\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\\\/\"},\"author\":{\"name\":\"ViajandoConVos\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#\\\/schema\\\/person\\\/b27882420b60d26e95d412d3c36d1d09\"},\"headline\":\"Chubut se suma al registro nacional de Agencias de Viajes de FAEVYT\",\"datePublished\":\"2025-01-28T13:21:23+00:00\",\"dateModified\":\"2025-01-28T13:21:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2025\\\/01\\\/28\\\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\\\/\"},\"wordCount\":244,\"publisher\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2025\\\/01\\\/28\\\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/5y3b9zFKNARvgJtdKXRjB8AWYkQAWLo7oHHSC0n8.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2025\\\/01\\\/28\\\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\\\/\",\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2025\\\/01\\\/28\\\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\\\/\",\"name\":\"Chubut se suma al registro nacional de Agencias de Viajes de FAEVYT - Viajando con vos con Quique Colombo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2025\\\/01\\\/28\\\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2025\\\/01\\\/28\\\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/5y3b9zFKNARvgJtdKXRjB8AWYkQAWLo7oHHSC0n8.jpg\",\"datePublished\":\"2025-01-28T13:21:23+00:00\",\"dateModified\":\"2025-01-28T13:21:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2025\\\/01\\\/28\\\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2025\\\/01\\\/28\\\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2025\\\/01\\\/28\\\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/5y3b9zFKNARvgJtdKXRjB8AWYkQAWLo7oHHSC0n8.jpg\",\"contentUrl\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/5y3b9zFKNARvgJtdKXRjB8AWYkQAWLo7oHHSC0n8.jpg\",\"width\":734,\"height\":1038},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2025\\\/01\\\/28\\\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chubut se suma al registro nacional de Agencias de Viajes de FAEVYT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/\",\"name\":\"Viajando con vos con Quique Colombo\",\"description\":\"Actualidad del sector Tur\u00edstico\",\"publisher\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#organization\",\"name\":\"Viajando con vos con Quique Colombo\",\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/logoviajando.png\",\"contentUrl\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/logoviajando.png\",\"width\":1920,\"height\":1080,\"caption\":\"Viajando con vos con Quique Colombo\"},\"image\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/quique.colombo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#\\\/schema\\\/person\\\/b27882420b60d26e95d412d3c36d1d09\",\"name\":\"ViajandoConVos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2af5c368ef9a4186064e78e63ca630a17d3fd3dafafde34561f548251a28ac0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2af5c368ef9a4186064e78e63ca630a17d3fd3dafafde34561f548251a28ac0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2af5c368ef9a4186064e78e63ca630a17d3fd3dafafde34561f548251a28ac0?s=96&d=mm&r=g\",\"caption\":\"ViajandoConVos\"},\"sameAs\":[\"http:\\\/\\\/deula\"],\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/author\\\/martin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chubut se suma al registro nacional de Agencias de Viajes de FAEVYT - Viajando con vos con Quique Colombo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/","og_locale":"es_ES","og_type":"article","og_title":"Chubut se suma al registro nacional de Agencias de Viajes de FAEVYT - Viajando con vos con Quique Colombo","og_description":"Se llev\u00f3 a cabo la firma del convenio de adhesi\u00f3n de la provincia de Chubut al Registro Nacional de Agencias de Viajes -RNAV-, con la presencia de Andr\u00e9s Dey\u00e1, presidente&#46;&#46;&#46;","og_url":"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/","og_site_name":"Viajando con vos con Quique Colombo","article_publisher":"https:\/\/www.facebook.com\/quique.colombo\/","article_published_time":"2025-01-28T13:21:23+00:00","article_modified_time":"2025-01-28T13:21:28+00:00","og_image":[{"width":734,"height":1038,"url":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/5y3b9zFKNARvgJtdKXRjB8AWYkQAWLo7oHHSC0n8.jpg","type":"image\/jpeg"}],"author":"ViajandoConVos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ViajandoConVos","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/#article","isPartOf":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/"},"author":{"name":"ViajandoConVos","@id":"https:\/\/viajandoconvos.com.ar\/wp\/#\/schema\/person\/b27882420b60d26e95d412d3c36d1d09"},"headline":"Chubut se suma al registro nacional de Agencias de Viajes de FAEVYT","datePublished":"2025-01-28T13:21:23+00:00","dateModified":"2025-01-28T13:21:28+00:00","mainEntityOfPage":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/"},"wordCount":244,"publisher":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/#organization"},"image":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/#primaryimage"},"thumbnailUrl":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/5y3b9zFKNARvgJtdKXRjB8AWYkQAWLo7oHHSC0n8.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/","url":"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/","name":"Chubut se suma al registro nacional de Agencias de Viajes de FAEVYT - Viajando con vos con Quique Colombo","isPartOf":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/#primaryimage"},"image":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/#primaryimage"},"thumbnailUrl":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/5y3b9zFKNARvgJtdKXRjB8AWYkQAWLo7oHHSC0n8.jpg","datePublished":"2025-01-28T13:21:23+00:00","dateModified":"2025-01-28T13:21:28+00:00","breadcrumb":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/#primaryimage","url":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/5y3b9zFKNARvgJtdKXRjB8AWYkQAWLo7oHHSC0n8.jpg","contentUrl":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/5y3b9zFKNARvgJtdKXRjB8AWYkQAWLo7oHHSC0n8.jpg","width":734,"height":1038},{"@type":"BreadcrumbList","@id":"https:\/\/viajandoconvos.com.ar\/wp\/2025\/01\/28\/chubut-se-suma-al-registro-nacional-de-agencias-de-viajes-de-faevyt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/viajandoconvos.com.ar\/wp\/"},{"@type":"ListItem","position":2,"name":"Chubut se suma al registro nacional de Agencias de Viajes de FAEVYT"}]},{"@type":"WebSite","@id":"https:\/\/viajandoconvos.com.ar\/wp\/#website","url":"https:\/\/viajandoconvos.com.ar\/wp\/","name":"Viajando con vos con Quique Colombo","description":"Actualidad del sector Tur\u00edstico","publisher":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/viajandoconvos.com.ar\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/viajandoconvos.com.ar\/wp\/#organization","name":"Viajando con vos con Quique Colombo","url":"https:\/\/viajandoconvos.com.ar\/wp\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/viajandoconvos.com.ar\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/logoviajando.png","contentUrl":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/logoviajando.png","width":1920,"height":1080,"caption":"Viajando con vos con Quique Colombo"},"image":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/quique.colombo\/"]},{"@type":"Person","@id":"https:\/\/viajandoconvos.com.ar\/wp\/#\/schema\/person\/b27882420b60d26e95d412d3c36d1d09","name":"ViajandoConVos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a2af5c368ef9a4186064e78e63ca630a17d3fd3dafafde34561f548251a28ac0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2af5c368ef9a4186064e78e63ca630a17d3fd3dafafde34561f548251a28ac0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2af5c368ef9a4186064e78e63ca630a17d3fd3dafafde34561f548251a28ac0?s=96&d=mm&r=g","caption":"ViajandoConVos"},"sameAs":["http:\/\/deula"],"url":"https:\/\/viajandoconvos.com.ar\/wp\/author\/martin\/"}]}},"_links":{"self":[{"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/posts\/9176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/comments?post=9176"}],"version-history":[{"count":1,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/posts\/9176\/revisions"}],"predecessor-version":[{"id":9178,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/posts\/9176\/revisions\/9178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/media\/9177"}],"wp:attachment":[{"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/media?parent=9176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/categories?post=9176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/tags?post=9176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}