{"id":6495,"date":"2022-06-13T11:56:18","date_gmt":"2022-06-13T14:56:18","guid":{"rendered":"https:\/\/viajandoconvos.com.ar\/wp\/?p=6495"},"modified":"2022-06-13T11:56:20","modified_gmt":"2022-06-13T14:56:20","slug":"el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico","status":"publish","type":"post","link":"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/","title":{"rendered":"El mar invita a vivir un invierno con excursiones n\u00e1uticas, fauna marina, buceo y un paisaje \u00fanico"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Aunque son los grandes protagonistas del verano, los destinos de la costa atl\u00e1ntica rionegrina se preparan con infinitas alternativas para que quienes decidan visitar la regi\u00f3n vivan unas vacaciones incre\u00edbles.<\/h4>\n\n\n\n<h6 class=\"wp-block-heading\">Fecha:&nbsp;<strong>12 de junio de 2022<\/strong><\/h6>\n\n\n\n<p class=\"wp-block-paragraph\">El Mar de R\u00edo Negro se alista para este invierno.Cr\u00e9dito:&nbsp;Gobierno de R\u00edo Negro<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un entorno natural donde reina la tranquilidad pero tambi\u00e9n divertidas aventuras para disfrutar en familia o con amigos, el Golfo San Mat\u00edas propone un plan perfecto para este invierno 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tentadora agenda involucra imperdibles avistajes de fauna marina y avifauna, buceo para expertos y principiantes en las profundidades del Golfo San Mat\u00edas, visitas a las m\u00edsticas Salinas del Gualicho y relax en las playas que conforman esta caracter\u00edstica regi\u00f3n de la provincia.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/silvercoder.rionegro.gov.ar\/files\/1655055282_e87e52917646ecf49c94.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Fauna marina en su m\u00e1xima expresi\u00f3n<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">La llegada de las vacaciones de invierno en la costa coincide con el arribo de los primeros ejemplares de ballena franca austral a las aguas de Las Grutas y el Puerto de San Antonio Este. Una salida embarcada de los prestadores habilitados de la zona permite a los y las visitantes observar de cerca a los distintos animales marinos que habitan la regi\u00f3n y aquellos que se trasladan a las m\u00e1s c\u00e1lidas aguas que ofrece el Golfo San Mat\u00edas, ambiente propicio para su reproducci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta aventura prometedora que no solo involucra a los imponentes cet\u00e1ceos, sino que tambi\u00e9n contempla la posibilidad de observar lobos marinos de uno o dos pelos y distintas especies de delfines que se suman a una gran variedad de aves caracter\u00edsticas de la zona como ping\u00fcinos, petreles, gaviotas y cormoranes playeros rojizos que brindan un espect\u00e1culo natural \u00fanico cerca de las embarcaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada salida implica una inc\u00f3gnita en s\u00ed misma, ya que es imposible saber con qu\u00e9 especies se va a topar durante el recorrido, lo que le da un toque especial a la actividad y la transforma en una opci\u00f3n s\u00faper tentadora para aquellos que deseen vivir una alternativa a las cl\u00e1sicas propuestas que tiene el balneario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale mencionar que aunque el pico de avistaje se da entre julio y octubre, hay grandes expectativas sobre el arribo de turistas de distintos puntos del pa\u00eds para la temporada de invierno. Adem\u00e1s los destinos costeros reciben contingentes provenientes de otras provincias para disfrutar de las experiencias en el mar como as\u00ed tambi\u00e9n en tierra firme.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/silvercoder.rionegro.gov.ar\/files\/1655055344_467e8e780e76469700b2.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Un viaje al fondo del mar<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Las y los amantes de la aventura acu\u00e1tica encontrar\u00e1n en Las Grutas la posibilidad de explorar la naturaleza marina que se forma entre los arrecifes artificiales que yacen en antiguas embarcaciones hundidas en las profundidades, en el marco de una propuesta que incluye impactantes traves\u00edas para buzos experimentados y bautismos enfocados en aquellos que quieran dar sus primeros pasos en esta inquietante actividad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta alternativa, que tiene al Parque Submarino Las Grutas como protagonista, permite visualizar en cada inmersi\u00f3n un sinf\u00edn de peces y crust\u00e1ceos que conforman el lecho marino del Golfo San Mat\u00edas, entre los que se encuentran cangrejos, esponjas, caracoles y otras especies.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El parque est\u00e1 conformado por cuatro buques pesqueros en desuso que fueron reacondicionados especialmente para la ocasi\u00f3n, a los que pr\u00f3ximamente se sumar\u00e1 el Magdalena Mar\u00eda que completar\u00e1 la primera etapa de hundimientos y permitir\u00e1 ubicar a este atractivo entre los m\u00e1s grandes de Latinoam\u00e9rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quienes se animen a vivir esta acci\u00f3n tambi\u00e9n tendr\u00e1n la posibilidad de visitar la cava submarina, donde descansan cientos de vinos rionegrinos a 15 metros de profundidad que fueron sumergidos en contenedores de acero inoxidable para llevar adelante un novedoso proceso de estacionamiento de las bebidas.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/silvercoder.rionegro.gov.ar\/files\/1655055443_be64c597b93ace11cc2f.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Un oasis de sal<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">A 50 kil\u00f3metros de Las Grutas se encuentran las Salinas del Gualicho, un atractivo maravilloso y plagado de misterios que invita a vivenciar una experiencia m\u00e1gica entre impresionantes vistas panor\u00e1micas que albergan uno de los atardeceres m\u00e1s bellos de la regi\u00f3n, caracterizado por el impresionante resplandor que se genera sobre el blanco espejo salino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata de unas salinas conformadas hace millones de a\u00f1os por la evaporaci\u00f3n de las aguas del mar que cubr\u00edan el lugar, que actualmente se presentan como una de las m\u00e1s extensas del pa\u00eds gracias a sus 35 kil\u00f3metros de ancho y 18 de largo y adem\u00e1s son consideradas unas de las m\u00e1s productivas de Sudam\u00e9rica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las excursiones al Gualicho, que parten desde el balneario grutense, incluyen una visita al Museo de la Sal, donde los visitantes podr\u00e1n adentrarse en el mundo de la producci\u00f3n salina, as\u00ed como tambi\u00e9n una interesante charla sobre las historias y leyendas que guarda este sitio tan particular, rodeado de misterios y mitos vinculados a fantasmas y dioses tehuelches. \u00bfEl broche de oro? Un brindis para coronar la salida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe destacar que para llegar hasta all\u00ed, se recomienda hacerlo a trav\u00e9s de la contrataci\u00f3n del servicio en agencias de viaje, con anticipaci\u00f3n y reserva previa ya que el acceso al p\u00fablico de manera particular se encuentra restringido debido a que se trata de un lugar donde se explotan recursos, por lo que es importante cuidar la integridad f\u00edsica de quienes las visitan.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/silvercoder.rionegro.gov.ar\/files\/1655055510_a7708dabcba48de7525d.jpg\" alt=\"\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Playas extensas para relajarse<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">En El C\u00f3ndor, a 30 kil\u00f3metros de Viedma, nace el Camino de la Costa, una ruta esc\u00e9nica que resguarda variadas playas que se caracterizan por su amplitud y tranquilidad y que invitan a ser disfrutadas a\u00fan durante el invierno, con distintas propuestas para toda la familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este balneario, que se presta para la pr\u00e1ctica de deportes de viento, tambi\u00e9n propone descubrir alguna de las 200 fascinantes especies que conforman el \u201cCielo de aves\u201d y embellecen los cielos de la regi\u00f3n mediante el avistaje de avifauna en alguno de los distintos circuitos que hay en el lugar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El C\u00f3ndor tambi\u00e9n resguarda dos sitios hist\u00f3ricos como el Faro R\u00edo Negro, una estructura de gran porte que recientemente cumpli\u00f3 130 a\u00f1os desde su fundaci\u00f3n, transform\u00e1ndose en el faro m\u00e1s antiguo en servicio del pa\u00eds y el m\u00e1s longevo de la Patagonia, mientras que a pocos metros de este espacio se sit\u00faa el Memorial de Malvinas, en memoria de los combatientes que batallaron en el hist\u00f3rico conflicto b\u00e9lico de 1982.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siguiendo la Ruta Provincial 1, que abre su paso un camino esc\u00e9nico con vistas privilegiadas sobre el mar, se arriba a La Lober\u00eda, un balneario resguardado por altos acantilados y a mil metros, Punta Bermeja, un \u00c1rea Natural Protegida que alberga de forma permanente a m\u00e1s de 6000 ejemplares de lobos marinos de un pelo llegando a 9000 en la temporada alta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Regi\u00f3n Mar de R\u00edo Negro propone variadas propuestas y alternativas para ser disfrutadas al m\u00e1ximo en estas vacaciones de julio y vivir un \u00a1Invierno \u00c9pico!.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque son los grandes protagonistas del verano, los destinos de la costa atl\u00e1ntica rionegrina se preparan con infinitas alternativas para que quienes decidan visitar la regi\u00f3n vivan unas vacaciones incre\u00edbles.&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":6496,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El mar invita a vivir un invierno con excursiones n\u00e1uticas, fauna marina, buceo y un paisaje \u00fanico - Viajando con vos con Quique Colombo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El mar invita a vivir un invierno con excursiones n\u00e1uticas, fauna marina, buceo y un paisaje \u00fanico - Viajando con vos con Quique Colombo\" \/>\n<meta property=\"og:description\" content=\"Aunque son los grandes protagonistas del verano, los destinos de la costa atl\u00e1ntica rionegrina se preparan con infinitas alternativas para que quienes decidan visitar la regi\u00f3n vivan unas vacaciones incre\u00edbles.&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/\" \/>\n<meta property=\"og:site_name\" content=\"Viajando con vos con Quique Colombo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quique.colombo\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-13T14:56:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-13T14:56:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/90f0228cf408ec176219020f555e4083.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ViajandoConVos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ViajandoConVos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2022\\\/06\\\/13\\\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2022\\\/06\\\/13\\\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\\\/\"},\"author\":{\"name\":\"ViajandoConVos\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#\\\/schema\\\/person\\\/b27882420b60d26e95d412d3c36d1d09\"},\"headline\":\"El mar invita a vivir un invierno con excursiones n\u00e1uticas, fauna marina, buceo y un paisaje \u00fanico\",\"datePublished\":\"2022-06-13T14:56:18+00:00\",\"dateModified\":\"2022-06-13T14:56:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2022\\\/06\\\/13\\\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\\\/\"},\"wordCount\":1195,\"publisher\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2022\\\/06\\\/13\\\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/90f0228cf408ec176219020f555e4083.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2022\\\/06\\\/13\\\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\\\/\",\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2022\\\/06\\\/13\\\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\\\/\",\"name\":\"El mar invita a vivir un invierno con excursiones n\u00e1uticas, fauna marina, buceo y un paisaje \u00fanico - Viajando con vos con Quique Colombo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2022\\\/06\\\/13\\\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2022\\\/06\\\/13\\\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/90f0228cf408ec176219020f555e4083.jpg\",\"datePublished\":\"2022-06-13T14:56:18+00:00\",\"dateModified\":\"2022-06-13T14:56:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2022\\\/06\\\/13\\\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2022\\\/06\\\/13\\\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2022\\\/06\\\/13\\\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/90f0228cf408ec176219020f555e4083.jpg\",\"contentUrl\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/90f0228cf408ec176219020f555e4083.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2022\\\/06\\\/13\\\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El mar invita a vivir un invierno con excursiones n\u00e1uticas, fauna marina, buceo y un paisaje \u00fanico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/\",\"name\":\"Viajando con vos con Quique Colombo\",\"description\":\"Actualidad del sector Tur\u00edstico\",\"publisher\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#organization\",\"name\":\"Viajando con vos con Quique Colombo\",\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/logoviajando.png\",\"contentUrl\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/logoviajando.png\",\"width\":1920,\"height\":1080,\"caption\":\"Viajando con vos con Quique Colombo\"},\"image\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/quique.colombo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#\\\/schema\\\/person\\\/b27882420b60d26e95d412d3c36d1d09\",\"name\":\"ViajandoConVos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2af5c368ef9a4186064e78e63ca630a17d3fd3dafafde34561f548251a28ac0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2af5c368ef9a4186064e78e63ca630a17d3fd3dafafde34561f548251a28ac0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a2af5c368ef9a4186064e78e63ca630a17d3fd3dafafde34561f548251a28ac0?s=96&d=mm&r=g\",\"caption\":\"ViajandoConVos\"},\"sameAs\":[\"http:\\\/\\\/deula\"],\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/author\\\/martin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El mar invita a vivir un invierno con excursiones n\u00e1uticas, fauna marina, buceo y un paisaje \u00fanico - Viajando con vos con Quique Colombo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/","og_locale":"es_ES","og_type":"article","og_title":"El mar invita a vivir un invierno con excursiones n\u00e1uticas, fauna marina, buceo y un paisaje \u00fanico - Viajando con vos con Quique Colombo","og_description":"Aunque son los grandes protagonistas del verano, los destinos de la costa atl\u00e1ntica rionegrina se preparan con infinitas alternativas para que quienes decidan visitar la regi\u00f3n vivan unas vacaciones incre\u00edbles.&#46;&#46;&#46;","og_url":"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/","og_site_name":"Viajando con vos con Quique Colombo","article_publisher":"https:\/\/www.facebook.com\/quique.colombo\/","article_published_time":"2022-06-13T14:56:18+00:00","article_modified_time":"2022-06-13T14:56:20+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/90f0228cf408ec176219020f555e4083.jpg","type":"image\/jpeg"}],"author":"ViajandoConVos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ViajandoConVos","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/#article","isPartOf":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/"},"author":{"name":"ViajandoConVos","@id":"https:\/\/viajandoconvos.com.ar\/wp\/#\/schema\/person\/b27882420b60d26e95d412d3c36d1d09"},"headline":"El mar invita a vivir un invierno con excursiones n\u00e1uticas, fauna marina, buceo y un paisaje \u00fanico","datePublished":"2022-06-13T14:56:18+00:00","dateModified":"2022-06-13T14:56:20+00:00","mainEntityOfPage":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/"},"wordCount":1195,"publisher":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/#organization"},"image":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/#primaryimage"},"thumbnailUrl":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/90f0228cf408ec176219020f555e4083.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/","url":"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/","name":"El mar invita a vivir un invierno con excursiones n\u00e1uticas, fauna marina, buceo y un paisaje \u00fanico - Viajando con vos con Quique Colombo","isPartOf":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/#primaryimage"},"image":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/#primaryimage"},"thumbnailUrl":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/90f0228cf408ec176219020f555e4083.jpg","datePublished":"2022-06-13T14:56:18+00:00","dateModified":"2022-06-13T14:56:20+00:00","breadcrumb":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/#primaryimage","url":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/90f0228cf408ec176219020f555e4083.jpg","contentUrl":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/90f0228cf408ec176219020f555e4083.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/viajandoconvos.com.ar\/wp\/2022\/06\/13\/el-mar-invita-a-vivir-un-invierno-con-excursiones-nauticas-fauna-marina-buceo-y-un-paisaje-unico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/viajandoconvos.com.ar\/wp\/"},{"@type":"ListItem","position":2,"name":"El mar invita a vivir un invierno con excursiones n\u00e1uticas, fauna marina, buceo y un paisaje \u00fanico"}]},{"@type":"WebSite","@id":"https:\/\/viajandoconvos.com.ar\/wp\/#website","url":"https:\/\/viajandoconvos.com.ar\/wp\/","name":"Viajando con vos con Quique Colombo","description":"Actualidad del sector Tur\u00edstico","publisher":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/viajandoconvos.com.ar\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/viajandoconvos.com.ar\/wp\/#organization","name":"Viajando con vos con Quique Colombo","url":"https:\/\/viajandoconvos.com.ar\/wp\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/viajandoconvos.com.ar\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/logoviajando.png","contentUrl":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/logoviajando.png","width":1920,"height":1080,"caption":"Viajando con vos con Quique Colombo"},"image":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/quique.colombo\/"]},{"@type":"Person","@id":"https:\/\/viajandoconvos.com.ar\/wp\/#\/schema\/person\/b27882420b60d26e95d412d3c36d1d09","name":"ViajandoConVos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a2af5c368ef9a4186064e78e63ca630a17d3fd3dafafde34561f548251a28ac0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a2af5c368ef9a4186064e78e63ca630a17d3fd3dafafde34561f548251a28ac0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a2af5c368ef9a4186064e78e63ca630a17d3fd3dafafde34561f548251a28ac0?s=96&d=mm&r=g","caption":"ViajandoConVos"},"sameAs":["http:\/\/deula"],"url":"https:\/\/viajandoconvos.com.ar\/wp\/author\/martin\/"}]}},"_links":{"self":[{"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/posts\/6495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/comments?post=6495"}],"version-history":[{"count":1,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/posts\/6495\/revisions"}],"predecessor-version":[{"id":6497,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/posts\/6495\/revisions\/6497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/media\/6496"}],"wp:attachment":[{"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/media?parent=6495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/categories?post=6495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/tags?post=6495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}