{"id":2173,"date":"2016-09-28T19:56:49","date_gmt":"2016-09-28T22:56:49","guid":{"rendered":"http:\/\/viajandoconvos.com.ar\/wp\/?p=2173"},"modified":"2016-09-28T19:56:49","modified_gmt":"2016-09-28T22:56:49","slug":"playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina","status":"publish","type":"post","link":"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/","title":{"rendered":"PLAYA HOTELS &#038; RESORTS CELEBRA SU LANZAMIENTO OFICIAL EN ARGENTINA"},"content":{"rendered":"<p><em>La reconocida cadena hotelera presento sus resorts todo incluido durante un evento con agentes de viajes, operadores y medios de comunicaci\u00f3n en Buenos Aires<\/em><\/p>\n<p>Playa Hotels &amp; Resorts, empresa propietaria, operadora y desarrolladora de resorts todo incluido en M\u00e9xico y el Caribe presento oficialmente sus marcas y sus propiedades en la ciudad de Buenos Aires durante un evento al que asistieron mas de 100 agentes de viajes, tour operadores y medios de comunicaci\u00f3n y que represento el lanzamiento oficial de la cadena en Argentina.<\/p>\n<p>La oferta hotelera de Playa Hotels &amp; Resorts incluye las marcas Hyatt Zilara, solo para adultos, y Hyatt Ziva, para hu\u00e9spedes de todas las edades, representadas por Hyatt Zilara Canc\u00fan, Hyatt Ziva Canc\u00fan, Hyatt Ziva Puerto Vallarta, Hyatt Ziva Los Cabos, Hyatt Zilara y Ziva Montego Bay \u2013 Jamaica, THE ROYAL Playa del Carmen, Gran Porto Playa del Carmen y Gran Caribe Canc\u00fan.<\/p>\n<p>\u201cEstamos muy contentos de lanzar nuestra <em>Evoluci\u00f3n del Todo<\/em> <em>Incluido<\/em>\u2122 <em>\u00a0<\/em>y nuestro <em>Servicio Desde El Coraz\u00f3n<\/em>\u2122 en un mercado tan importante como el argentino\u201d dijo Wally Dagri, Director de Relaciones Publicas de Playa Hotels &amp; Resorts. \u201c<\/p>\n<p>La ubicaci\u00f3n inigualable de nuestros resorts en cada destino, sus hermosas playas, el cari\u00f1o genuino de nuestros empleados al atender a los huespedes, la oferta gastronomica gourmet y las lujosas habitaciones son solamente algunos de los aspectos que enamorar\u00e0n al viajero argentino. Nosotros no ofrecemos estancias, ofrecemos experiencias, y nos gustaria que mas y mas argentinos fueran a gozar de esas experiencias unicas en Mexico y Jamaica\u201d a\u00f1adi\u00f2 Dagri.<\/p>\n<p>Por su parte Giovanni Lara, Gerente de Ventas para Latino America de Playa Hotels &amp; Resorts coment\u00f2: \u201cQueremos fortalecer nuestra presencia en Argentina , estar mas cerca de los tour operadores y de las agencias de viaje.<\/p>\n<p>Es tan importante este pais para nuestra empresa que muy pronto tendremos un representante para Argentina, Uruguay y Paraguay, \u00a0para brindar una atencion mas personalizada a nuestros partners comerciales, realizando acciones en conjunto e incrementando asi nuestros negocios mutuamente\u201d.<\/p>\n<p>Playa Hotels &amp; Resorts estar\u00e0 presente del 1 al 4 de Octubre en FIT 2016 con un espacio en el pabellon de Mexico.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Acerca de Playa Hotels &amp; Resorts<\/strong><\/p>\n<p>Con una colecci\u00f3n de 9 lujosas propiedades que suman mas de 3.500 habitaciones, todas ubicadas en las mejores playas de M\u00e9xico y Jamaica, Playa Hotels &amp; Resort, BV (Playa) es una empresa propietaria, operadora y desarrolladora de resorts todo incluido. Playa posee y opera Hyatt Ziva Los Cabos, Hyatt Zilara Canc\u00fan, Hyatt Ziva Cancun, Hyatt Ziva y Zilara Rose Hall, Jamaica y Hyatt Ziva Puerto Vallarta. La empresa tambi\u00e9n posee y opera 3 resorts bajo las marcas THE ROYAL y Gran. Gracias a un acuerdo con una filial de Hyatt Hotels Corporation (NYSE:H) Playa seguir\u00e1 con la adquisici\u00f3n y desarrollo de nuevos resorts bajos las nuevas marcas todo incluido de Hyatt: Hyatt Ziva y Hyatt Zilara. Playa tambi\u00e9n cuenta con un acuerdo de exclusividad para operar resorts todo incluido de Hyatt en 5 pa\u00edses de Latinoam\u00e9rica y el Caribe. Para m\u00e1s informaci\u00f3n visite: www.playaresorts.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La reconocida cadena hotelera presento sus resorts todo incluido durante un evento con agentes de viajes, operadores y medios de comunicaci\u00f3n en Buenos Aires Playa Hotels &amp; Resorts, empresa propietaria,&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":2174,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PLAYA HOTELS &amp; RESORTS CELEBRA SU LANZAMIENTO OFICIAL EN ARGENTINA - Viajando con vos con Quique Colombo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PLAYA HOTELS &amp; RESORTS CELEBRA SU LANZAMIENTO OFICIAL EN ARGENTINA - Viajando con vos con Quique Colombo\" \/>\n<meta property=\"og:description\" content=\"La reconocida cadena hotelera presento sus resorts todo incluido durante un evento con agentes de viajes, operadores y medios de comunicaci\u00f3n en Buenos Aires Playa Hotels &amp; Resorts, empresa propietaria,&#046;&#046;&#046;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/\" \/>\n<meta property=\"og:site_name\" content=\"Viajando con vos con Quique Colombo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quique.colombo\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-28T22:56:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/IMG_1548.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3264\" \/>\n\t<meta property=\"og:image:height\" content=\"2448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"quique colombo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"quique colombo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2016\\\/09\\\/28\\\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2016\\\/09\\\/28\\\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\\\/\"},\"author\":{\"name\":\"quique colombo\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#\\\/schema\\\/person\\\/23a217edc6d2bf1c431512da58d2e41b\"},\"headline\":\"PLAYA HOTELS &#038; RESORTS CELEBRA SU LANZAMIENTO OFICIAL EN ARGENTINA\",\"datePublished\":\"2016-09-28T22:56:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2016\\\/09\\\/28\\\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\\\/\"},\"wordCount\":528,\"publisher\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2016\\\/09\\\/28\\\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/IMG_1548.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2016\\\/09\\\/28\\\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\\\/\",\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2016\\\/09\\\/28\\\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\\\/\",\"name\":\"PLAYA HOTELS & RESORTS CELEBRA SU LANZAMIENTO OFICIAL EN ARGENTINA - Viajando con vos con Quique Colombo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2016\\\/09\\\/28\\\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2016\\\/09\\\/28\\\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/IMG_1548.jpg\",\"datePublished\":\"2016-09-28T22:56:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2016\\\/09\\\/28\\\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2016\\\/09\\\/28\\\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2016\\\/09\\\/28\\\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/IMG_1548.jpg\",\"contentUrl\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/IMG_1548.jpg\",\"width\":3264,\"height\":2448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/2016\\\/09\\\/28\\\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PLAYA HOTELS &#038; RESORTS CELEBRA SU LANZAMIENTO OFICIAL EN ARGENTINA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#website\",\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/\",\"name\":\"Viajando con vos con Quique Colombo\",\"description\":\"Actualidad del sector Tur\u00edstico\",\"publisher\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#organization\",\"name\":\"Viajando con vos con Quique Colombo\",\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/logoviajando.png\",\"contentUrl\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/wp-content\\\/uploads\\\/logoviajando.png\",\"width\":1920,\"height\":1080,\"caption\":\"Viajando con vos con Quique Colombo\"},\"image\":{\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/quique.colombo\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/#\\\/schema\\\/person\\\/23a217edc6d2bf1c431512da58d2e41b\",\"name\":\"quique colombo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f9f95344662de91dc9d9453612cd5091e708c8876a1d3cd2597729491128f6e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f9f95344662de91dc9d9453612cd5091e708c8876a1d3cd2597729491128f6e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f9f95344662de91dc9d9453612cd5091e708c8876a1d3cd2597729491128f6e?s=96&d=mm&r=g\",\"caption\":\"quique colombo\"},\"url\":\"https:\\\/\\\/viajandoconvos.com.ar\\\/wp\\\/author\\\/quique\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PLAYA HOTELS & RESORTS CELEBRA SU LANZAMIENTO OFICIAL EN ARGENTINA - Viajando con vos con Quique Colombo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/","og_locale":"es_ES","og_type":"article","og_title":"PLAYA HOTELS & RESORTS CELEBRA SU LANZAMIENTO OFICIAL EN ARGENTINA - Viajando con vos con Quique Colombo","og_description":"La reconocida cadena hotelera presento sus resorts todo incluido durante un evento con agentes de viajes, operadores y medios de comunicaci\u00f3n en Buenos Aires Playa Hotels &amp; Resorts, empresa propietaria,&#46;&#46;&#46;","og_url":"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/","og_site_name":"Viajando con vos con Quique Colombo","article_publisher":"https:\/\/www.facebook.com\/quique.colombo\/","article_published_time":"2016-09-28T22:56:49+00:00","og_image":[{"width":3264,"height":2448,"url":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/IMG_1548.jpg","type":"image\/jpeg"}],"author":"quique colombo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"quique colombo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/#article","isPartOf":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/"},"author":{"name":"quique colombo","@id":"https:\/\/viajandoconvos.com.ar\/wp\/#\/schema\/person\/23a217edc6d2bf1c431512da58d2e41b"},"headline":"PLAYA HOTELS &#038; RESORTS CELEBRA SU LANZAMIENTO OFICIAL EN ARGENTINA","datePublished":"2016-09-28T22:56:49+00:00","mainEntityOfPage":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/"},"wordCount":528,"publisher":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/#organization"},"image":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/#primaryimage"},"thumbnailUrl":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/IMG_1548.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/","url":"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/","name":"PLAYA HOTELS & RESORTS CELEBRA SU LANZAMIENTO OFICIAL EN ARGENTINA - Viajando con vos con Quique Colombo","isPartOf":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/#primaryimage"},"image":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/#primaryimage"},"thumbnailUrl":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/IMG_1548.jpg","datePublished":"2016-09-28T22:56:49+00:00","breadcrumb":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/#primaryimage","url":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/IMG_1548.jpg","contentUrl":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/IMG_1548.jpg","width":3264,"height":2448},{"@type":"BreadcrumbList","@id":"https:\/\/viajandoconvos.com.ar\/wp\/2016\/09\/28\/playa-hotels-resorts-celebra-su-lanzamiento-oficial-en-argentina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/viajandoconvos.com.ar\/wp\/"},{"@type":"ListItem","position":2,"name":"PLAYA HOTELS &#038; RESORTS CELEBRA SU LANZAMIENTO OFICIAL EN ARGENTINA"}]},{"@type":"WebSite","@id":"https:\/\/viajandoconvos.com.ar\/wp\/#website","url":"https:\/\/viajandoconvos.com.ar\/wp\/","name":"Viajando con vos con Quique Colombo","description":"Actualidad del sector Tur\u00edstico","publisher":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/viajandoconvos.com.ar\/wp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/viajandoconvos.com.ar\/wp\/#organization","name":"Viajando con vos con Quique Colombo","url":"https:\/\/viajandoconvos.com.ar\/wp\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/viajandoconvos.com.ar\/wp\/#\/schema\/logo\/image\/","url":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/logoviajando.png","contentUrl":"https:\/\/viajandoconvos.com.ar\/wp\/wp-content\/uploads\/logoviajando.png","width":1920,"height":1080,"caption":"Viajando con vos con Quique Colombo"},"image":{"@id":"https:\/\/viajandoconvos.com.ar\/wp\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/quique.colombo\/"]},{"@type":"Person","@id":"https:\/\/viajandoconvos.com.ar\/wp\/#\/schema\/person\/23a217edc6d2bf1c431512da58d2e41b","name":"quique colombo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4f9f95344662de91dc9d9453612cd5091e708c8876a1d3cd2597729491128f6e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f9f95344662de91dc9d9453612cd5091e708c8876a1d3cd2597729491128f6e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f9f95344662de91dc9d9453612cd5091e708c8876a1d3cd2597729491128f6e?s=96&d=mm&r=g","caption":"quique colombo"},"url":"https:\/\/viajandoconvos.com.ar\/wp\/author\/quique\/"}]}},"_links":{"self":[{"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/posts\/2173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/comments?post=2173"}],"version-history":[{"count":1,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/posts\/2173\/revisions"}],"predecessor-version":[{"id":2175,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/posts\/2173\/revisions\/2175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/media\/2174"}],"wp:attachment":[{"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/media?parent=2173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/categories?post=2173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/viajandoconvos.com.ar\/wp\/wp-json\/wp\/v2\/tags?post=2173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}